{"id":9880,"date":"2022-04-11T15:47:54","date_gmt":"2022-04-11T13:47:54","guid":{"rendered":"https:\/\/www.tornabuoni1.com\/2022\/04\/11\/the-tower-permanent-exhibition-new-works-by-lena-keslin\/"},"modified":"2022-04-12T14:21:28","modified_gmt":"2022-04-12T12:21:28","slug":"la-mostra-permanente-della-torre-nuove-opere-di-lena-keslin","status":"publish","type":"post","link":"https:\/\/www.tornabuoni1.com\/it\/2022\/04\/11\/la-mostra-permanente-della-torre-nuove-opere-di-lena-keslin\/","title":{"rendered":"La mostra permanente della Torre: Nuove opere di Lena Keslin"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text]Se avete gi\u00e0 soggiornato all&#8217;Antica Torre Tornabuoni avrete notato che la nostra Torre respira arte. Alle pareti, oltre agli affreschi, i nostri ospiti trovano ispirazione da dipinti di molti artisti e anche <a href=\"https:\/\/www.tornabuoni1.com\/it\/2021\/05\/20\/la-mostra-permanente-della-torre-intervista-a-lena-keslin\/\">la Mostra Permanente con le foto di Lena Keslin<\/a>, che sa immortalare Firenze come nessun altro.<\/p>\n<p>La mostra di 25 grandi foto su tela presenta ora sei nuovi pezzi, portati dall\u2019artista stessa dopo un lungo periodo lontano da Firenze. \u201cOriginariamente dovevamo arrivare a Firenze il 12 marzo 2020 per consegnare sei grandi fotografie su tela alla nostra amata Antica Torre di Via Tornabuoni,1. Tuttavia, quello si \u00e8 rivelato lo stesso giorno in cui tutta l&#8217;Italia \u00e8 stata chiusa\u201d, dice Lena. \u201cIl mondo si \u00e8 chiuso ed \u00e8 stato un periodo spaventoso. Viviamo a Santa Fe e lavoriamo fuori casa, quindi siamo stati fortunati a non vivere in una grande citt\u00e0. Avevamo la spesa consegnata, ma mai da asporto&#8230; Ho cucinato tre pasti al giorno per oltre un anno. Ho letto molti libri e lavorato su alcuni progetti auto-creati. Ma \u00e8 stato un periodo orribile, abbiamo perso cari amici e familiari. Ero preoccupata per i nostri amici a Firenze, il nostro albergo preferito, i nostri ristoranti preferiti&#8230; Sapevo che l&#8217;Italia era stata colpita duramente e che tutti quelli che conoscevo l\u00ec venivano colpiti\u201d.<\/p>\n<p>Dopo due anni e una settimana (come ha voluto sottolineare), Lena \u00e8 finalmente arrivata a Firenze il primo giorno di primavera del 2022. \u201c\u00c8 un sogno diventato realt\u00e0, essere tornata e accolta nella nostra bellissima camera all&#8217;Antica Torre \u00e8 stato tutto quello che mi aspettavo. Ammirare il Duomo o attraversare l&#8217;Arno con vedute che sembravano dipinte da Da Vinci.\u201d Risponde Lena.<\/p>\n<p>Ecco i nuovi lavori della Mostra Permanente di Lena Keslin all&#8217;Antica Torre Tornabuoni, spiegati dall\u2019artista stessa.<\/p>\n<p>&nbsp;<\/p>\n<h4><strong>Under the Vasari Corridor (Sotto il Corridoio Vasariano)<\/strong><\/h4>\n<p>\u00c8 una foto senza persone. Ho notato altrove che le foto di quell&#8217;arco sono diventate la rappresentazione delle strade vuote di Firenze durante la pandemia. Una mattina mi sono alzata molto presto per uscire a fotografare gli archi, sperando di trovare le strade vuote, non immaginando quale significato avrebbero rappresentato.<\/p>\n<p>&nbsp;<\/p>\n<h4><strong>Farmacia di San Marco<\/strong><\/h4>\n<p>\u00c8 uno dei miei preferiti di questa nuova collezione. Amo l&#8217;edificio e le iscrizioni di ci\u00f2 che \u00e8 stato commerciato in quel luogo magico. Deve avere una storia molto interessante e antica. Questo \u00e8 stato il mio omaggio al suo antico splendore.<\/p>\n<p>&nbsp;<\/p>\n<h4><strong>Bargello Interior (Interno del Bargello)<\/strong><\/h4>\n<p>Qui sottolineerei l&#8217;uso elegante dello spazio con sculture e archi e il pavimento piastrellato e aperto agli elementi del tempo.<\/p>\n<p>&nbsp;<\/p>\n<h4><strong>The Curtain (La tenda)<\/strong><\/h4>\n<p>\u00c8 in tessuto drappeggiato, con la luce dall&#8217;esterno che risplende attraverso una finestra di Palazzo Pitti.<\/p>\n<p>&nbsp;<\/p>\n<h4><strong>The Corridor (Il Corridoio)<\/strong><\/h4>\n<p>Sta guardando in un corridoio di Palazzo Davanzati, un luogo che continua a ispirare con uno sguardo su com&#8217;era una casa rinascimentale.<\/p>\n<p>&nbsp;<\/p>\n<h4><strong>The Uffizi Ceiling (Il soffitto degli Uffizi)<\/strong><\/h4>\n<p>Questa \u00e8 una rappresentazione cos\u00ec elegante del design fiorentino.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<div id=\"attachment_9860\" style=\"width: 1031px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-9860\" class=\"wp-image-9860 size-full\" src=\"https:\/\/www.tornabuoni1.com\/wp-content\/uploads\/IMG_6600.jpg\" alt=\"Lena Keslin Exhibition\" width=\"1021\" height=\"753\" srcset=\"https:\/\/www.tornabuoni1.com\/wp-content\/uploads\/IMG_6600.jpg 1021w, https:\/\/www.tornabuoni1.com\/wp-content\/uploads\/IMG_6600-300x221.jpg 300w\" sizes=\"auto, (max-width: 1021px) 100vw, 1021px\" \/><p id=\"caption-attachment-9860\" class=\"wp-caption-text\">I sei nuovi pezzi in mostra all&#8217;Antica Torre Tornabuoni, di Lena Keslin: (in banco, da sinistra a destra) The Corridor, Farmacia di San Marco, Under the Vasari Corridor; (sul pavimento, da sinistra a destra) Bargello Interior, The Curtain, The Uffizi Ceiling<\/p><\/div>\n<p>&nbsp;<\/p>\n<p>Queste nuove aggiunte alla collezione si trovano nelle camere degli ospiti e nei corridoi del 4\u00b0 e 5\u00b0 piano della Torre.<\/p>\n<p>&nbsp;<\/p>\n<p><em>Foto: Michael Keslin<\/em>[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text]Se avete gi\u00e0 soggiornato all&#8217;Antica Torre Tornabuoni avrete notato che la nostra Torre respira arte. Alle pareti, oltre agli affreschi, i nostri ospiti trovano ispirazione da dipinti di molti artisti e anche la Mostra Permanente con le foto di Lena Keslin, che sa immortalare Firenze come nessun altro. La mostra di 25 grandi foto su [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":9863,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[114],"tags":[805],"class_list":["post-9880","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog-it","tag-lena-keslin-it"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La mostra permanente della Torre: Nuove opere di Lena Keslin<\/title>\n<meta name=\"description\" content=\"Ecco i nuovi lavori della Mostra Permanente di Lena Keslin all&#039;Antica Torre Tornabuoni, spiegati dall&#039;artista stessa.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tornabuoni1.com\/it\/2022\/04\/11\/la-mostra-permanente-della-torre-nuove-opere-di-lena-keslin\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La mostra permanente della Torre: Nuove opere di Lena Keslin\" \/>\n<meta property=\"og:description\" content=\"Ecco i nuovi lavori della Mostra Permanente di Lena Keslin all&#039;Antica Torre Tornabuoni, spiegati dall&#039;artista stessa.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tornabuoni1.com\/it\/2022\/04\/11\/la-mostra-permanente-della-torre-nuove-opere-di-lena-keslin\/\" \/>\n<meta property=\"og:site_name\" content=\"Antica Torre di Via Tornabuoni 1\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/anticatorretornabuoni\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-11T13:47:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-12T12:21:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tornabuoni1.com\/wp-content\/uploads\/Lena-Keslin_wp.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1040\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Antica Torre\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Antica Torre\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tornabuoni1.com\\\/it\\\/2022\\\/04\\\/11\\\/la-mostra-permanente-della-torre-nuove-opere-di-lena-keslin\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tornabuoni1.com\\\/it\\\/2022\\\/04\\\/11\\\/la-mostra-permanente-della-torre-nuove-opere-di-lena-keslin\\\/\"},\"author\":{\"name\":\"Antica Torre\",\"@id\":\"https:\\\/\\\/www.tornabuoni1.com\\\/it\\\/#\\\/schema\\\/person\\\/be711ab02e2f7e9c71500a3a87520f14\"},\"headline\":\"La mostra permanente della Torre: Nuove opere di Lena Keslin\",\"datePublished\":\"2022-04-11T13:47:54+00:00\",\"dateModified\":\"2022-04-12T12:21:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tornabuoni1.com\\\/it\\\/2022\\\/04\\\/11\\\/la-mostra-permanente-della-torre-nuove-opere-di-lena-keslin\\\/\"},\"wordCount\":571,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tornabuoni1.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tornabuoni1.com\\\/it\\\/2022\\\/04\\\/11\\\/la-mostra-permanente-della-torre-nuove-opere-di-lena-keslin\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tornabuoni1.com\\\/wp-content\\\/uploads\\\/Lena-Keslin_wp.png\",\"keywords\":[\"Lena Keslin\"],\"articleSection\":[\"Blog IT\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.tornabuoni1.com\\\/it\\\/2022\\\/04\\\/11\\\/la-mostra-permanente-della-torre-nuove-opere-di-lena-keslin\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tornabuoni1.com\\\/it\\\/2022\\\/04\\\/11\\\/la-mostra-permanente-della-torre-nuove-opere-di-lena-keslin\\\/\",\"url\":\"https:\\\/\\\/www.tornabuoni1.com\\\/it\\\/2022\\\/04\\\/11\\\/la-mostra-permanente-della-torre-nuove-opere-di-lena-keslin\\\/\",\"name\":\"La mostra permanente della Torre: Nuove opere di Lena Keslin\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tornabuoni1.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tornabuoni1.com\\\/it\\\/2022\\\/04\\\/11\\\/la-mostra-permanente-della-torre-nuove-opere-di-lena-keslin\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tornabuoni1.com\\\/it\\\/2022\\\/04\\\/11\\\/la-mostra-permanente-della-torre-nuove-opere-di-lena-keslin\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tornabuoni1.com\\\/wp-content\\\/uploads\\\/Lena-Keslin_wp.png\",\"datePublished\":\"2022-04-11T13:47:54+00:00\",\"dateModified\":\"2022-04-12T12:21:28+00:00\",\"description\":\"Ecco i nuovi lavori della Mostra Permanente di Lena Keslin all'Antica Torre Tornabuoni, spiegati dall'artista stessa.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tornabuoni1.com\\\/it\\\/2022\\\/04\\\/11\\\/la-mostra-permanente-della-torre-nuove-opere-di-lena-keslin\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tornabuoni1.com\\\/it\\\/2022\\\/04\\\/11\\\/la-mostra-permanente-della-torre-nuove-opere-di-lena-keslin\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tornabuoni1.com\\\/it\\\/2022\\\/04\\\/11\\\/la-mostra-permanente-della-torre-nuove-opere-di-lena-keslin\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tornabuoni1.com\\\/wp-content\\\/uploads\\\/Lena-Keslin_wp.png\",\"contentUrl\":\"https:\\\/\\\/www.tornabuoni1.com\\\/wp-content\\\/uploads\\\/Lena-Keslin_wp.png\",\"width\":1040,\"height\":600,\"caption\":\"Lena Keslin\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tornabuoni1.com\\\/it\\\/2022\\\/04\\\/11\\\/la-mostra-permanente-della-torre-nuove-opere-di-lena-keslin\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tornabuoni1.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La mostra permanente della Torre: Nuove opere di Lena Keslin\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tornabuoni1.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.tornabuoni1.com\\\/it\\\/\",\"name\":\"Antica Torre di Via Tornabuoni 1\",\"description\":\"Antica Torre di Via Tornabuoni 1\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tornabuoni1.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tornabuoni1.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.tornabuoni1.com\\\/it\\\/#organization\",\"name\":\"Antica Torre di Via Tornabuoni 1\",\"alternateName\":\"Antica Torre\",\"url\":\"https:\\\/\\\/www.tornabuoni1.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tornabuoni1.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.tornabuoni1.com\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/AT2_quadrato.png\",\"contentUrl\":\"https:\\\/\\\/www.tornabuoni1.com\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/AT2_quadrato.png\",\"width\":192,\"height\":192,\"caption\":\"Antica Torre di Via Tornabuoni 1\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tornabuoni1.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/anticatorretornabuoni\",\"https:\\\/\\\/www.instagram.com\\\/tornabuoni_anticatorre\\\/\",\"https:\\\/\\\/www.pinterest.it\\\/anticatorre\\\/_created\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tornabuoni1.com\\\/it\\\/#\\\/schema\\\/person\\\/be711ab02e2f7e9c71500a3a87520f14\",\"name\":\"Antica Torre\",\"url\":\"https:\\\/\\\/www.tornabuoni1.com\\\/it\\\/author\\\/daniele\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La mostra permanente della Torre: Nuove opere di Lena Keslin","description":"Ecco i nuovi lavori della Mostra Permanente di Lena Keslin all'Antica Torre Tornabuoni, spiegati dall'artista stessa.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tornabuoni1.com\/it\/2022\/04\/11\/la-mostra-permanente-della-torre-nuove-opere-di-lena-keslin\/","og_locale":"it_IT","og_type":"article","og_title":"La mostra permanente della Torre: Nuove opere di Lena Keslin","og_description":"Ecco i nuovi lavori della Mostra Permanente di Lena Keslin all'Antica Torre Tornabuoni, spiegati dall'artista stessa.","og_url":"https:\/\/www.tornabuoni1.com\/it\/2022\/04\/11\/la-mostra-permanente-della-torre-nuove-opere-di-lena-keslin\/","og_site_name":"Antica Torre di Via Tornabuoni 1","article_publisher":"https:\/\/www.facebook.com\/anticatorretornabuoni","article_published_time":"2022-04-11T13:47:54+00:00","article_modified_time":"2022-04-12T12:21:28+00:00","og_image":[{"width":1040,"height":600,"url":"https:\/\/www.tornabuoni1.com\/wp-content\/uploads\/Lena-Keslin_wp.png","type":"image\/png"}],"author":"Antica Torre","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Antica Torre","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tornabuoni1.com\/it\/2022\/04\/11\/la-mostra-permanente-della-torre-nuove-opere-di-lena-keslin\/#article","isPartOf":{"@id":"https:\/\/www.tornabuoni1.com\/it\/2022\/04\/11\/la-mostra-permanente-della-torre-nuove-opere-di-lena-keslin\/"},"author":{"name":"Antica Torre","@id":"https:\/\/www.tornabuoni1.com\/it\/#\/schema\/person\/be711ab02e2f7e9c71500a3a87520f14"},"headline":"La mostra permanente della Torre: Nuove opere di Lena Keslin","datePublished":"2022-04-11T13:47:54+00:00","dateModified":"2022-04-12T12:21:28+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tornabuoni1.com\/it\/2022\/04\/11\/la-mostra-permanente-della-torre-nuove-opere-di-lena-keslin\/"},"wordCount":571,"commentCount":0,"publisher":{"@id":"https:\/\/www.tornabuoni1.com\/it\/#organization"},"image":{"@id":"https:\/\/www.tornabuoni1.com\/it\/2022\/04\/11\/la-mostra-permanente-della-torre-nuove-opere-di-lena-keslin\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tornabuoni1.com\/wp-content\/uploads\/Lena-Keslin_wp.png","keywords":["Lena Keslin"],"articleSection":["Blog IT"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.tornabuoni1.com\/it\/2022\/04\/11\/la-mostra-permanente-della-torre-nuove-opere-di-lena-keslin\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.tornabuoni1.com\/it\/2022\/04\/11\/la-mostra-permanente-della-torre-nuove-opere-di-lena-keslin\/","url":"https:\/\/www.tornabuoni1.com\/it\/2022\/04\/11\/la-mostra-permanente-della-torre-nuove-opere-di-lena-keslin\/","name":"La mostra permanente della Torre: Nuove opere di Lena Keslin","isPartOf":{"@id":"https:\/\/www.tornabuoni1.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tornabuoni1.com\/it\/2022\/04\/11\/la-mostra-permanente-della-torre-nuove-opere-di-lena-keslin\/#primaryimage"},"image":{"@id":"https:\/\/www.tornabuoni1.com\/it\/2022\/04\/11\/la-mostra-permanente-della-torre-nuove-opere-di-lena-keslin\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tornabuoni1.com\/wp-content\/uploads\/Lena-Keslin_wp.png","datePublished":"2022-04-11T13:47:54+00:00","dateModified":"2022-04-12T12:21:28+00:00","description":"Ecco i nuovi lavori della Mostra Permanente di Lena Keslin all'Antica Torre Tornabuoni, spiegati dall'artista stessa.","breadcrumb":{"@id":"https:\/\/www.tornabuoni1.com\/it\/2022\/04\/11\/la-mostra-permanente-della-torre-nuove-opere-di-lena-keslin\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tornabuoni1.com\/it\/2022\/04\/11\/la-mostra-permanente-della-torre-nuove-opere-di-lena-keslin\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tornabuoni1.com\/it\/2022\/04\/11\/la-mostra-permanente-della-torre-nuove-opere-di-lena-keslin\/#primaryimage","url":"https:\/\/www.tornabuoni1.com\/wp-content\/uploads\/Lena-Keslin_wp.png","contentUrl":"https:\/\/www.tornabuoni1.com\/wp-content\/uploads\/Lena-Keslin_wp.png","width":1040,"height":600,"caption":"Lena Keslin"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tornabuoni1.com\/it\/2022\/04\/11\/la-mostra-permanente-della-torre-nuove-opere-di-lena-keslin\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tornabuoni1.com\/it\/"},{"@type":"ListItem","position":2,"name":"La mostra permanente della Torre: Nuove opere di Lena Keslin"}]},{"@type":"WebSite","@id":"https:\/\/www.tornabuoni1.com\/it\/#website","url":"https:\/\/www.tornabuoni1.com\/it\/","name":"Antica Torre di Via Tornabuoni 1","description":"Antica Torre di Via Tornabuoni 1","publisher":{"@id":"https:\/\/www.tornabuoni1.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tornabuoni1.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.tornabuoni1.com\/it\/#organization","name":"Antica Torre di Via Tornabuoni 1","alternateName":"Antica Torre","url":"https:\/\/www.tornabuoni1.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tornabuoni1.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.tornabuoni1.com\/wp-content\/uploads\/2016\/01\/AT2_quadrato.png","contentUrl":"https:\/\/www.tornabuoni1.com\/wp-content\/uploads\/2016\/01\/AT2_quadrato.png","width":192,"height":192,"caption":"Antica Torre di Via Tornabuoni 1"},"image":{"@id":"https:\/\/www.tornabuoni1.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/anticatorretornabuoni","https:\/\/www.instagram.com\/tornabuoni_anticatorre\/","https:\/\/www.pinterest.it\/anticatorre\/_created\/"]},{"@type":"Person","@id":"https:\/\/www.tornabuoni1.com\/it\/#\/schema\/person\/be711ab02e2f7e9c71500a3a87520f14","name":"Antica Torre","url":"https:\/\/www.tornabuoni1.com\/it\/author\/daniele\/"}]}},"_links":{"self":[{"href":"https:\/\/www.tornabuoni1.com\/it\/wp-json\/wp\/v2\/posts\/9880","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tornabuoni1.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tornabuoni1.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tornabuoni1.com\/it\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tornabuoni1.com\/it\/wp-json\/wp\/v2\/comments?post=9880"}],"version-history":[{"count":3,"href":"https:\/\/www.tornabuoni1.com\/it\/wp-json\/wp\/v2\/posts\/9880\/revisions"}],"predecessor-version":[{"id":9883,"href":"https:\/\/www.tornabuoni1.com\/it\/wp-json\/wp\/v2\/posts\/9880\/revisions\/9883"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tornabuoni1.com\/it\/wp-json\/wp\/v2\/media\/9863"}],"wp:attachment":[{"href":"https:\/\/www.tornabuoni1.com\/it\/wp-json\/wp\/v2\/media?parent=9880"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tornabuoni1.com\/it\/wp-json\/wp\/v2\/categories?post=9880"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tornabuoni1.com\/it\/wp-json\/wp\/v2\/tags?post=9880"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}